{"id":5142,"date":"2020-05-05T16:10:42","date_gmt":"2020-05-05T16:10:42","guid":{"rendered":"https:\/\/www.isdin.com\/es\/blog\/?p=5142"},"modified":"2023-06-07T16:10:30","modified_gmt":"2023-06-07T16:10:30","slug":"como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel","status":"publish","type":"post","link":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/","title":{"rendered":"Luc\u00eda Gal\u00e1n, pediatra, resuelve nuestras dudas sobre c\u00f3mo afecta la situaci\u00f3n actual a los ni\u00f1os y a su piel"},"content":{"rendered":"<p>Los ni\u00f1os tienen una capacidad de adaptaci\u00f3n y aceptaci\u00f3n espectacular y estos d\u00edas nos lo est\u00e1n demostrando. Hemos hablado con Luc\u00eda Gal\u00e1n, pediatra, que nos ha contado c\u00f3mo est\u00e1n viviendo los m\u00e1s peque\u00f1os esta situaci\u00f3n y ha resuelto nuestras dudas sobre c\u00f3mo cuidarlos, proteger su piel y gestionar con ellos el momento actual.<\/p>\n<h2>\u00bfC\u00f3mo est\u00e1n viviendo los ni\u00f1os esta situaci\u00f3n?<\/h2>\n<p>los efectos a corto plazo que hemos podido ver en consulta son trastornos del sue\u00f1o, rabietas, pesadillas e incremento de sonambulismos. Sin embargo, no esperamos que el impacto a medio-largo plazo sea importante. Cuando recuperemos la normalidad, los efectos que vemos estos d\u00edas desaparecer\u00e1n.<\/p>\n<p>En cuanto al impacto psicol\u00f3gico, depende fundamentalmente de c\u00f3mo lo estemos viviendo los adultos. Si nosotros lo vivimos desde la serenidad y la calma, ellos lo vivir\u00e1n tambi\u00e9n de esta manera. Nuestros hijos no van a recordar las estad\u00edsticas ni los n\u00fameros. Recordar\u00e1n c\u00f3mo se han sentido en casa. Es importante ser conscientes de ello, intentar tenerlo en cuenta, reflexionar y darles lo mejor de nosotros. Se lo merecen.<\/p>\n<blockquote class=\"\"><p>\u201cNuestros hijos no van a recordar las estad\u00edsticas ni los n\u00fameros. Recordar\u00e1n c\u00f3mo se han sentido en casa. Es importante ser conscientes de ello, intentar tenerlo en cuenta, reflexionar y darles lo mejor de nosotros. Se lo merecen.\u201d<\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5151 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_famlia.jpg\" alt=\"\" width=\"670\" height=\"449\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_famlia.jpg 670w, https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_famlia-150x101.jpg 150w, https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_famlia-300x201.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><\/p>\n<h3>La comunicaci\u00f3n es clave<\/h3>\n<p>Los ni\u00f1os lo entienden todo, a veces los adultos nos creamos prejuicios y pensamos que algo no les sentar\u00e1 bien o se van a frustrar, pero todo depende de c\u00f3mo lo comuniquemos. Es importante explicarles las cosas como son, darles las gracias por el esfuerzo tan importante que est\u00e1n haciendo y plantear las situaciones de manera positiva, como un juego.<\/p>\n<h2><span style=\"font-weight: 400;\">\u00bfQu\u00e9 efectos tiene en su piel?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Nuestro <\/span><a href=\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-el-estres-a-nuestra-piel\/\"><span style=\"font-weight: 400;\">estado emocional<\/span><\/a><span style=\"font-weight: 400;\"> est\u00e1 \u00edntimamente ligado con el estado de nuestra piel. Toda situaci\u00f3n que nos saque de nuestra zona de tranquilidad, de confort, puede afectar a nuestra piel. En el campo de la pediatr\u00eda, relacionado con la piel, estamos viendo, sobre todo, m\u00e1s brotes de <\/span><a href=\"https:\/\/www.isdin.com\/marcas\/nutratopic\/\"><span style=\"font-weight: 400;\">dermatitis at\u00f3pica<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h3>Piel at\u00f3pica<\/h3>\n<p>El ambiente reseco de las casas, el exceso de abrigo cuando salimos y el estr\u00e9s empeoran estos brotes. Adem\u00e1s, estamos en \u00e9poca de alergias y los ni\u00f1os que tienen rinitis al\u00e9rgica en muchos casos tienen dermatitis at\u00f3pica.<\/p>\n<p>Las caracter\u00edsticas principales de la piel de los ni\u00f1os que tienen dermatitis at\u00f3pica son: <strong>picor y sequedad<\/strong> (xerosis cut\u00e1nea). Tienen la barrera de la piel alterada, mucho m\u00e1s sensible y seca. Esta sequedad produce picor, el ni\u00f1o se rasca y se produce una reacci\u00f3n inflamatoria, lo que empeora a\u00fan m\u00e1s el picor, creando un c\u00edrculo vicioso.<\/p>\n<p><span style=\"font-weight: 400;\">La <\/span><b>hidrataci\u00f3n<\/b><span style=\"font-weight: 400;\"> es clave para prevenir los brotes de dermatitis at\u00f3pica. Se recomienda utilizar <\/span><a href=\"https:\/\/www.isdin.com\/producto\/nutratopic\/crema-emoliente-piel-atopica\"><span style=\"font-weight: 400;\">cremas emolientes<\/span><\/a><span style=\"font-weight: 400;\">, espec\u00edficamente formuladas para la piel de los ni\u00f1os, e huir de cremas que tengan mucho perfume, ya que podr\u00edan irritar su piel.<\/span><\/p>\n<blockquote class=\"\"><p>\u201cLa hidrataci\u00f3n es clave para prevenir los brotes de dermatitis at\u00f3pica. Se recomienda utilizar cremas emolientes, espec\u00edficamente formuladas para la piel de los ni\u00f1os, e huir de cremas que tengan mucho perfume, ya que podr\u00edan irritar su piel.\u201d<\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5152 lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_atopia.jpg\" alt=\"\" width=\"670\" height=\"449\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_atopia.jpg 670w, https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_atopia-150x101.jpg 150w, https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_atopia-300x201.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><\/span><\/p>\n<h2><span style=\"font-weight: 400;\">\u00bfLa piel de los ni\u00f1os es m\u00e1s sensible?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La piel es la primera barrera defensiva de nuestro cuerpo y, en el caso de los ni\u00f1os, tambi\u00e9n ayuda a mantener su temperatura corporal. Su piel es m\u00e1s sensible, delicada y reactiva ante agresiones externas. Por eso es tan importante utilizar<\/span><a href=\"https:\/\/www.isdin.com\/marcas\/isdin-baby-naturals\/\"> <span style=\"font-weight: 400;\">productos<\/span><\/a><span style=\"font-weight: 400;\"> espec\u00edficamente formulados para ellos. Los cosm\u00e9ticos que usamos los adultos no suelen estar testados en ni\u00f1os y beb\u00e9s. Adem\u00e1s, no compartimos el mismo tipo de piel.<\/span><\/p>\n<blockquote class=\"\"><p>\u201cLa piel es la primera barrera defensiva de nuestro cuerpo y, en el caso de los ni\u00f1os, tambi\u00e9n ayuda a mantener su temperatura corporal. Su piel es m\u00e1s sensible, delicada y reactiva ante agresiones externas. Por eso es tan importante utilizar productos espec\u00edficamente formulados para ellos.\u201d<\/p><\/blockquote>\n<h3>\u00bfC\u00f3mo va a reaccionar su piel al sol despu\u00e9s de tanto tiempo sin exponernos?<\/h3>\n<p>Los pediatras llevamos semanas insistiendo en la importancia de la vitamina D. Los ni\u00f1os pueden estar al sol sin protector solar 10 minutos para metabolizar la vitamina D y no les pasar\u00e1 nada, pero m\u00e1s all\u00e1 de eso, y ahora que ya empezamos a entrar en una \u00e9poca en la que va a empezar a hacer m\u00e1s sol y calor, tenemos que acostumbrarnos a usar filtros solares en todas las edades.<\/p>\n<p>Debemos tener en cuenta que el 80% de los melanomas ser\u00edan prevenibles si hubi\u00e9semos hecho una protecci\u00f3n adecuada de la piel desde peque\u00f1os. La piel tiene memoria y el c\u00e1ncer de adultos es consecuencia de toda la radiaci\u00f3n solar que ha ido sumando nuestra piel. Es muy importante proteger a nuestros hijos del sol desde peque\u00f1os con filtros adecuados y educarles en ello.<\/p>\n<blockquote class=\"\"><p>\u201cEl 80% de los melanomas ser\u00edan prevenibles si hubi\u00e9semos hecho una protecci\u00f3n adecuada de la piel desde peque\u00f1os. [\u2026] Es muy importante proteger a nuestros hijos del sol desde peque\u00f1os con filtros adecuados y educarles en ello.\u201d<\/p><\/blockquote>\n<h3><span style=\"font-weight: 400;\">\u00bfC\u00f3mo explicamos a los ni\u00f1os la importancia de usar protector solar y tener buenos h\u00e1bitos de fotoprotecci\u00f3n?<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Si convertimos el momento de aplicarnos <\/span><a href=\"https:\/\/www.isdin.com\/protector-solar\/ninos-bebes\/?gclid=EAIaIQobChMI1MjG_7Ga6QIVk_dRCh3vQgtvEAAYAiAAEgKBr_D_BwE\"><span style=\"font-weight: 400;\">protecci\u00f3n solar<\/span><\/a><span style=\"font-weight: 400;\"> en un juego y un momento positivo, conseguiremos que adopten el h\u00e1bito. Tambi\u00e9n es importante proteger nuestra piel delante de ellos, hacerlo juntos y dar ejemplo.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">\u00bfC\u00f3mo escoger el mejor protector solar para ellos?<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">La caracter\u00edsticas m\u00e1s importantes que debe tener un protector solar pedi\u00e1trico son que est\u00e9 testado dermatol\u00f3gicamente en ni\u00f1os, que tenga un SPF alto, 50, y que se extienda bien, sin dejar residuo pegajoso. Ser\u00eda un plus que tambi\u00e9n est\u00e9 testado en pieles at\u00f3picas \u00a1y que no irrite los ojos! Como pediatra y como madre, su cosmeticidad tambi\u00e9n es muy importante. Al ni\u00f1o le tiene que gustar el protector solar, si le gusta, querr\u00e1 ponerselo.<\/span><\/p>\n<blockquote class=\"\"><p>\u201cLa caracter\u00edsticas m\u00e1s importantes que debe tener un protector solar pedi\u00e1trico son que est\u00e9 testado dermatol\u00f3gicamente en ni\u00f1os, que tenga un SPF alto, 50, y que se extienda bien, sin dejar residuo pegajoso. Ser\u00eda un plus que tambi\u00e9n est\u00e9 testado en pieles at\u00f3picas \u00a1y que no irrite los ojos!\u201d<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Los ni\u00f1os tienen una capacidad de adaptaci\u00f3n y aceptaci\u00f3n espectacular y estos d\u00edas nos lo est\u00e1n demostrando. Hemos hablado con Luc\u00eda Gal\u00e1n, pediatra, que nos ha contado c\u00f3mo est\u00e1n viviendo los m\u00e1s peque\u00f1os esta situaci\u00f3n y ha resuelto nuestras dudas sobre c\u00f3mo cuidarlos, proteger su piel y gestionar con ellos el momento actual. \u00bfC\u00f3mo est\u00e1n&hellip;<\/p>\n","protected":false},"author":3,"featured_media":5149,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[65,287],"tags":[],"class_list":["post-5142","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-expertos","category-pediatria","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v25.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Luc\u00eda Gal\u00e1n, pediatra, resuelve nuestras dudas sobre c\u00f3mo afecta la situaci\u00f3n actual a los ni\u00f1os y a su piel - ISDIN<\/title>\n<meta name=\"description\" content=\"\u00bfQuieres saber c\u00f3mo afecta la situaci\u00f3n actual a la piel de los ni\u00f1os y c\u00f3mo cuidarla y protegerla? Hemos hablado con Luc\u00eda Gal\u00e1n, pediatra.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luc\u00eda Gal\u00e1n, pediatra, resuelve nuestras dudas sobre c\u00f3mo afecta la situaci\u00f3n actual a los ni\u00f1os y a su piel\" \/>\n<meta property=\"og:description\" content=\"\u00bfQuieres saber c\u00f3mo afecta la situaci\u00f3n actual a la piel de los ni\u00f1os y c\u00f3mo cuidarla y protegerla? Hemos hablado con Luc\u00eda Gal\u00e1n, pediatra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/\" \/>\n<meta property=\"og:site_name\" content=\"ISDIN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/ISDIN.official\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-05T16:10:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-07T16:10:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_portada_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Live Young\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@isdin_official\" \/>\n<meta name=\"twitter:site\" content=\"@isdin_official\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Live Young\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/\"},\"author\":{\"name\":\"Live Young\",\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/#\/schema\/person\/528848368b26d62008cefcc29a52ade8\"},\"headline\":\"Luc\u00eda Gal\u00e1n, pediatra, resuelve nuestras dudas sobre c\u00f3mo afecta la situaci\u00f3n actual a los ni\u00f1os y a su piel\",\"datePublished\":\"2020-05-05T16:10:42+00:00\",\"dateModified\":\"2023-06-07T16:10:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/\"},\"wordCount\":1145,\"publisher\":{\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_portada.jpg\",\"articleSection\":[\"Expertos\",\"Pediatr\u00eda\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/\",\"url\":\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/\",\"name\":\"Luc\u00eda Gal\u00e1n, pediatra, resuelve nuestras dudas sobre c\u00f3mo afecta la situaci\u00f3n actual a los ni\u00f1os y a su piel - ISDIN\",\"isPartOf\":{\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_portada.jpg\",\"datePublished\":\"2020-05-05T16:10:42+00:00\",\"dateModified\":\"2023-06-07T16:10:30+00:00\",\"description\":\"\u00bfQuieres saber c\u00f3mo afecta la situaci\u00f3n actual a la piel de los ni\u00f1os y c\u00f3mo cuidarla y protegerla? Hemos hablado con Luc\u00eda Gal\u00e1n, pediatra.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#primaryimage\",\"url\":\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_portada.jpg\",\"contentUrl\":\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_portada.jpg\",\"width\":1200,\"height\":761},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.isdin.com\/es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luc\u00eda Gal\u00e1n, pediatra, resuelve nuestras dudas sobre c\u00f3mo afecta la situaci\u00f3n actual a los ni\u00f1os y a su piel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/#website\",\"url\":\"https:\/\/www.isdin.com\/es\/blog\/\",\"name\":\"ISDIN\",\"description\":\"Novedades, lanzamientos de productos y toda la experiencia de ISDIN\",\"publisher\":{\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.isdin.com\/es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/#organization\",\"name\":\"ISDIN\",\"alternateName\":\"ISDIN\",\"url\":\"https:\/\/www.isdin.com\/es\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2024\/05\/2025_03_GuiaFoto_FWM.png\",\"contentUrl\":\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2024\/05\/2025_03_GuiaFoto_FWM.png\",\"width\":670,\"height\":683,\"caption\":\"ISDIN\"},\"image\":{\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/es-es.facebook.com\/ISDIN.official\/\",\"https:\/\/x.com\/isdin_official\",\"https:\/\/www.instagram.com\/isdinofficial\",\"https:\/\/www.youtube.com\/channel\/UCtoNJMKpDwdFLqgV23_lcqg\"],\"telephone\":\"659997812\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/#\/schema\/person\/528848368b26d62008cefcc29a52ade8\",\"name\":\"Live Young\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.isdin.com\/es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2017\/07\/isdin-live-young-150x150-1.png\",\"contentUrl\":\"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2017\/07\/isdin-live-young-150x150-1.png\",\"caption\":\"Live Young\"},\"description\":\"Nuestro hom\u00f3nimo encarna el esp\u00edritu de abrazar la vida y todas sus maravillas. Como periodistas especializaciones en la salud y bienestar de la piel, exploramos temas que vigorizan los sentidos y mantienen viva la curiosidad. Creemos que una piel radiante es el resultado de un cuerpo y una mente saludables. Tejiendo belleza con ciencia, nuestro objetivo es inspirarte a vivir joven en cada edad.\",\"url\":\"https:\/\/www.isdin.com\/es\/blog\/author\/love-your-skin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Luc\u00eda Gal\u00e1n, pediatra, resuelve nuestras dudas sobre c\u00f3mo afecta la situaci\u00f3n actual a los ni\u00f1os y a su piel - ISDIN","description":"\u00bfQuieres saber c\u00f3mo afecta la situaci\u00f3n actual a la piel de los ni\u00f1os y c\u00f3mo cuidarla y protegerla? Hemos hablado con Luc\u00eda Gal\u00e1n, pediatra.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/","og_locale":"es_ES","og_type":"article","og_title":"Luc\u00eda Gal\u00e1n, pediatra, resuelve nuestras dudas sobre c\u00f3mo afecta la situaci\u00f3n actual a los ni\u00f1os y a su piel","og_description":"\u00bfQuieres saber c\u00f3mo afecta la situaci\u00f3n actual a la piel de los ni\u00f1os y c\u00f3mo cuidarla y protegerla? Hemos hablado con Luc\u00eda Gal\u00e1n, pediatra.","og_url":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/","og_site_name":"ISDIN","article_publisher":"https:\/\/es-es.facebook.com\/ISDIN.official\/","article_published_time":"2020-05-05T16:10:42+00:00","article_modified_time":"2023-06-07T16:10:30+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_portada_fb.jpg","type":"image\/jpeg"}],"author":"Live Young","twitter_card":"summary_large_image","twitter_creator":"@isdin_official","twitter_site":"@isdin_official","twitter_misc":{"Written by":"Live Young","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#article","isPartOf":{"@id":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/"},"author":{"name":"Live Young","@id":"https:\/\/www.isdin.com\/es\/blog\/#\/schema\/person\/528848368b26d62008cefcc29a52ade8"},"headline":"Luc\u00eda Gal\u00e1n, pediatra, resuelve nuestras dudas sobre c\u00f3mo afecta la situaci\u00f3n actual a los ni\u00f1os y a su piel","datePublished":"2020-05-05T16:10:42+00:00","dateModified":"2023-06-07T16:10:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/"},"wordCount":1145,"publisher":{"@id":"https:\/\/www.isdin.com\/es\/blog\/#organization"},"image":{"@id":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_portada.jpg","articleSection":["Expertos","Pediatr\u00eda"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/","url":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/","name":"Luc\u00eda Gal\u00e1n, pediatra, resuelve nuestras dudas sobre c\u00f3mo afecta la situaci\u00f3n actual a los ni\u00f1os y a su piel - ISDIN","isPartOf":{"@id":"https:\/\/www.isdin.com\/es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#primaryimage"},"image":{"@id":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_portada.jpg","datePublished":"2020-05-05T16:10:42+00:00","dateModified":"2023-06-07T16:10:30+00:00","description":"\u00bfQuieres saber c\u00f3mo afecta la situaci\u00f3n actual a la piel de los ni\u00f1os y c\u00f3mo cuidarla y protegerla? Hemos hablado con Luc\u00eda Gal\u00e1n, pediatra.","breadcrumb":{"@id":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#primaryimage","url":"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_portada.jpg","contentUrl":"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2020\/05\/Piel_de_los_ninos_Lucia_Galan_pediatra_portada.jpg","width":1200,"height":761},{"@type":"BreadcrumbList","@id":"https:\/\/www.isdin.com\/es\/blog\/como-afecta-la-situacion-actual-a-los-ninos-y-a-su-piel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.isdin.com\/es\/blog\/"},{"@type":"ListItem","position":2,"name":"Luc\u00eda Gal\u00e1n, pediatra, resuelve nuestras dudas sobre c\u00f3mo afecta la situaci\u00f3n actual a los ni\u00f1os y a su piel"}]},{"@type":"WebSite","@id":"https:\/\/www.isdin.com\/es\/blog\/#website","url":"https:\/\/www.isdin.com\/es\/blog\/","name":"ISDIN","description":"Novedades, lanzamientos de productos y toda la experiencia de ISDIN","publisher":{"@id":"https:\/\/www.isdin.com\/es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.isdin.com\/es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.isdin.com\/es\/blog\/#organization","name":"ISDIN","alternateName":"ISDIN","url":"https:\/\/www.isdin.com\/es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.isdin.com\/es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2024\/05\/2025_03_GuiaFoto_FWM.png","contentUrl":"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2024\/05\/2025_03_GuiaFoto_FWM.png","width":670,"height":683,"caption":"ISDIN"},"image":{"@id":"https:\/\/www.isdin.com\/es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/ISDIN.official\/","https:\/\/x.com\/isdin_official","https:\/\/www.instagram.com\/isdinofficial","https:\/\/www.youtube.com\/channel\/UCtoNJMKpDwdFLqgV23_lcqg"],"telephone":"659997812"},{"@type":"Person","@id":"https:\/\/www.isdin.com\/es\/blog\/#\/schema\/person\/528848368b26d62008cefcc29a52ade8","name":"Live Young","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.isdin.com\/es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2017\/07\/isdin-live-young-150x150-1.png","contentUrl":"https:\/\/www.isdin.com\/es\/blog\/wp-content\/uploads\/2017\/07\/isdin-live-young-150x150-1.png","caption":"Live Young"},"description":"Nuestro hom\u00f3nimo encarna el esp\u00edritu de abrazar la vida y todas sus maravillas. Como periodistas especializaciones en la salud y bienestar de la piel, exploramos temas que vigorizan los sentidos y mantienen viva la curiosidad. Creemos que una piel radiante es el resultado de un cuerpo y una mente saludables. Tejiendo belleza con ciencia, nuestro objetivo es inspirarte a vivir joven en cada edad.","url":"https:\/\/www.isdin.com\/es\/blog\/author\/love-your-skin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.isdin.com\/es\/blog\/wp-json\/wp\/v2\/posts\/5142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.isdin.com\/es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.isdin.com\/es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.isdin.com\/es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.isdin.com\/es\/blog\/wp-json\/wp\/v2\/comments?post=5142"}],"version-history":[{"count":10,"href":"https:\/\/www.isdin.com\/es\/blog\/wp-json\/wp\/v2\/posts\/5142\/revisions"}],"predecessor-version":[{"id":8109,"href":"https:\/\/www.isdin.com\/es\/blog\/wp-json\/wp\/v2\/posts\/5142\/revisions\/8109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.isdin.com\/es\/blog\/wp-json\/wp\/v2\/media\/5149"}],"wp:attachment":[{"href":"https:\/\/www.isdin.com\/es\/blog\/wp-json\/wp\/v2\/media?parent=5142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.isdin.com\/es\/blog\/wp-json\/wp\/v2\/categories?post=5142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.isdin.com\/es\/blog\/wp-json\/wp\/v2\/tags?post=5142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}